  {"id":5668,"date":"2023-07-26T09:31:48","date_gmt":"2023-07-26T14:31:48","guid":{"rendered":"https:\/\/www.missouriwestern.edu\/music\/event\/sjcc-and-chamber-singers-rehearsal\/"},"modified":"2023-08-28T14:08:37","modified_gmt":"2023-08-28T19:08:37","slug":"sjcc-and-chamber-singers-rehearsal","status":"publish","type":"tribe_events","link":"https:\/\/www.missouriwestern.edu\/music\/event\/sjcc-and-chamber-singers-rehearsal\/","title":{"rendered":"SJCC and Chamber Singers Rehearsal"},"content":{"rendered":"<p><b>Description:<\/b><br \/><b>Rehearsal for Chamber Singers &amp; SJCC<br \/><\/b><br \/><b>Organizer Information:<\/b><br \/>Please reach out to Cheryl Rasmussen\u00a0<a href=\"mailto:crasmussen60@gmail.com\"><u>crasmussen60@gmail.com<\/u><\/a>\u00a0for additional information.<\/p>\n<p><b>Admission:<\/b><br \/>This is only for Chamber Singers &amp; SJCC Members<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Description:Rehearsal for Chamber Singers &amp; SJCCOrganizer Information:Please reach out to Cheryl Rasmussen\u00a0crasmussen60@gmail.com\u00a0for additional information. Admission:This is only for Chamber Singers &amp; SJCC Members<\/p>\n","protected":false},"author":71,"featured_media":0,"template":"","meta":{"_acf_changed":false,"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":"","_tec_slr_enabled":"","_tec_slr_layout":""},"tags":[],"tribe_events_cat":[32],"class_list":["post-5668","tribe_events","type-tribe_events","status-publish","hentry","tribe_events_cat-choirs","cat_choirs"],"acf":[],"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"ticketed":false,"_links":{"self":[{"href":"https:\/\/www.missouriwestern.edu\/music\/wp-json\/wp\/v2\/tribe_events\/5668","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.missouriwestern.edu\/music\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.missouriwestern.edu\/music\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.missouriwestern.edu\/music\/wp-json\/wp\/v2\/users\/71"}],"version-history":[{"count":1,"href":"https:\/\/www.missouriwestern.edu\/music\/wp-json\/wp\/v2\/tribe_events\/5668\/revisions"}],"predecessor-version":[{"id":5852,"href":"https:\/\/www.missouriwestern.edu\/music\/wp-json\/wp\/v2\/tribe_events\/5668\/revisions\/5852"}],"wp:attachment":[{"href":"https:\/\/www.missouriwestern.edu\/music\/wp-json\/wp\/v2\/media?parent=5668"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.missouriwestern.edu\/music\/wp-json\/wp\/v2\/tags?post=5668"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.missouriwestern.edu\/music\/wp-json\/wp\/v2\/tribe_events_cat?post=5668"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}